{"id":240,"date":"2024-06-30T21:20:31","date_gmt":"2024-06-30T21:20:31","guid":{"rendered":"https:\/\/sarandidigital.com\/uy\/?p=240"},"modified":"2024-06-30T21:20:31","modified_gmt":"2024-06-30T21:20:31","slug":"una-fiesta-civica-con-pocos-invitados","status":"publish","type":"post","link":"https:\/\/sarandidigital.com\/uy\/una-fiesta-civica-con-pocos-invitados\/","title":{"rendered":"Una fiesta c\u00edvica&#8230; con pocos invitados"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/IMG-20240630-WA0014.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/IMG-20240630-WA0014-1024x768.jpg\" alt=\"\" class=\"wp-image-241\" srcset=\"https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/IMG-20240630-WA0014-1024x768.jpg 1024w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/IMG-20240630-WA0014-300x225.jpg 300w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/IMG-20240630-WA0014-768x576.jpg 768w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/IMG-20240630-WA0014-1536x1152.jpg 1536w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/IMG-20240630-WA0014.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><em><strong>Soledad L\u00f3pez de Encuentro Renovador vot\u00f3 en el Liceo poco m\u00e1s all\u00e1 de las 15.30 horas<\/strong><\/em><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>En cada celebraci\u00f3n que se precie de tal la cantidad de participantes importa. Y mucho. No es lo mismo un festejo entre pocos que una fiesta con muchos. Y en las elecciones sucede lo mismo.<\/p>\n\n\n\n<p>Las elecciones internas, definidas por todos como una fiesta c\u00edvica, cont\u00f3 con muy pocos invitados. La baja participaci\u00f3n de electores llev\u00f3 a que el tema del domingo 30 de junio \u2013adem\u00e1s del fr\u00edo polar reinante- fuera recurrente.<\/p>\n\n\n\n<p>Las preguntas surg\u00edas desde los periodistas a los candidatos, desde los referentes a sus delegados, desde los votantes a sus pares. \u00bfPoca gente, verdad? Muy poca, era la respuesta. A medida que el sol ca\u00eda en la tarde g\u00e9lida del domingo, los puntos de participaci\u00f3n comenzaban a vaciarse de p\u00fablico y solamente los integrantes de mesa, seguridad y delegados pugnaban por apurar el reloj hacia las 19.39 horas como \u00faltimo instante de participaci\u00f3n ciudadana.<\/p>\n\n\n\n<p>As\u00ed sucedi\u00f3, sin excepciones, en todo el departamento y el pa\u00eds. La Corte Electoral se encarg\u00f3 de suministrar las cantidades exactas de participantes en horas pico. A las 15 horas, seg\u00fan datos oficiales, en el departamento de Florida hab\u00edan sufragado 14511 personas, nucleando ciudades y pueblos, circuitos de escuelas rurales y puntos c\u00e9ntricos.<\/p>\n\n\n\n<p>De esa manera el 35% del total habilitado, y poco m\u00e1s, se acercaba a las urnas para definir los candidatos presidenciales de cada partido pol\u00edtico y los participantes en las convenciones departamentales y nacionales.<\/p>\n\n\n\n<p>El mejor clima<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/IMG-20240630-WA0011.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"766\" height=\"1024\" src=\"https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/IMG-20240630-WA0011-766x1024.jpg\" alt=\"\" class=\"wp-image-242\" srcset=\"https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/IMG-20240630-WA0011-766x1024.jpg 766w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/IMG-20240630-WA0011-224x300.jpg 224w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/IMG-20240630-WA0011-768x1027.jpg 768w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/IMG-20240630-WA0011-1149x1536.jpg 1149w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/IMG-20240630-WA0011.jpg 1179w\" sizes=\"auto, (max-width: 766px) 100vw, 766px\" \/><\/a><figcaption class=\"wp-element-caption\"><strong><em>Tano Stopingi sufrag\u00f3 en el Liceo Faustino Harrison a las 16 horas<\/em><\/strong><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Ajenos al fr\u00edo, los sarandienses sobrellevaron nuevamente una instancia pac\u00edfica de votaciones, con sana convivencia entre los participantes. As\u00ed fue destacado desde las filas pol\u00edticas con las cuales tuvimos contacto durante la jornada. Los delegados identificados con sus colores y n\u00fameros partidarios pudieron convivir alejados de rencillas de campa\u00f1a. Los saludos de siempre, los reconocimientos para tantos coterr\u00e1neos que se acercan a su ciudad desde los actuales puntos de residencia y el habitual intercambio de besos, abrazos y an\u00e9cdotas que eso conlleva.<\/p>\n\n\n\n<p>El clima electoral ya se vivi\u00f3 desde el s\u00e1bado, cuando las carnicer\u00edas de la ciudad agotaron sus stocks de asado, cuando los supermercados y almacenes dieron cuenta de \u201cmuy buenas ventas\u201d, especialmente familias que se reencuentran en torno a la mesa del s\u00e1bado a la noche y domingo al mediod\u00eda, con el voto interno como excusa v\u00e1lida.<\/p>\n\n\n\n<p>Al tiempo que este medio recorr\u00eda los puntos de votaci\u00f3n, diferentes medios de comunicaci\u00f3n de la capital departamental emitieron desde Sarand\u00ed Grande durante determinados puntos del d\u00eda, tomando en cuenta la existencia de figuras de relevancia departamental en esta contienda. Tano Stopingi, Soledad L\u00f3pez, Omar Gonz\u00e1lez, Nicol\u00e1s Vaz, fueron algunos de los votos que la televisi\u00f3n y radio de la ciudad de Florida siguieron de cerca, ya fuera desde la Escuela N\u00ba 113, Liceo Faustino Harrison, Escuelas 7 y 38, Centro Cultural, Club Deportivo Social Sarand\u00ed o Centro Social 12 de Octubre.<\/p>\n\n\n\n<p>A la nochecita, al caer la tarde junto con el sol y la helada del \u00faltimo d\u00eda de junio, ya era invisible el movimiento popular en la ciudad. Llamados a sus hogares, solo quedaba aguardar el escrutinio y conocer qu\u00e9 figuras competir\u00e1n en octubre \u2013eventualmente en noviembre- para definir el futuro Presidente del pa\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/20240630_170216-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/20240630_170216-1024x576.jpg\" alt=\"\" class=\"wp-image-243\" srcset=\"https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/20240630_170216-1024x576.jpg 1024w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/20240630_170216-300x169.jpg 300w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/20240630_170216-768x432.jpg 768w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/20240630_170216-1536x864.jpg 1536w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2024\/06\/20240630_170216-2048x1153.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\"><strong><em>Nicol\u00e1s Vaz, del Partido Socialista, le toc\u00f3 votar en la Escuela 113 a las 17 horas<\/em><\/strong><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En cada celebraci\u00f3n que se precie de tal la cantidad de participantes importa. Y mucho. No es lo mismo un festejo entre pocos que una fiesta con muchos. Y en las elecciones sucede lo mismo. Las elecciones internas, definidas por todos como una fiesta c\u00edvica, cont\u00f3 con muy pocos invitados. La baja participaci\u00f3n de electores [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-240","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/posts\/240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/comments?post=240"}],"version-history":[{"count":1,"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/posts\/240\/revisions"}],"predecessor-version":[{"id":244,"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/posts\/240\/revisions\/244"}],"wp:attachment":[{"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/media?parent=240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/categories?post=240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/tags?post=240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}