{"id":575,"date":"2026-05-12T21:57:09","date_gmt":"2026-05-12T21:57:09","guid":{"rendered":"https:\/\/sarandidigital.com\/uy\/?p=575"},"modified":"2026-05-12T21:57:09","modified_gmt":"2026-05-12T21:57:09","slug":"santi-garcia-el-joven-sarandiense-que-suena-con-llegar-a-la-pantalla-grande-y-participa-de-una-produccion-de-amazon-di-el-primer-paso-hacia-lo-grande-que-se-viene","status":"publish","type":"post","link":"https:\/\/sarandidigital.com\/uy\/santi-garcia-el-joven-sarandiense-que-suena-con-llegar-a-la-pantalla-grande-y-participa-de-una-produccion-de-amazon-di-el-primer-paso-hacia-lo-grande-que-se-viene\/","title":{"rendered":"Santi Garc\u00eda, el joven sarandiense que sue\u00f1a con llegar a la pantalla grande y participa de una producci\u00f3n de Amazon: \u201cDi el primer paso hacia lo grande que se viene\u201d"},"content":{"rendered":"\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2026\/05\/Nota-santi-Garcia.mp3\"><\/audio><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong><em>Entrevista mantenida con el joven actor en el Noticiero &#8216;Siglo XXI&#8217;<\/em><\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2026\/05\/Santi-en-accion-rodando-por-vez-primera.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"577\" height=\"1024\" src=\"https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2026\/05\/Santi-en-accion-rodando-por-vez-primera-577x1024.jpg\" alt=\"\" class=\"wp-image-577\" srcset=\"https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2026\/05\/Santi-en-accion-rodando-por-vez-primera-577x1024.jpg 577w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2026\/05\/Santi-en-accion-rodando-por-vez-primera-169x300.jpg 169w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2026\/05\/Santi-en-accion-rodando-por-vez-primera-768x1363.jpg 768w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2026\/05\/Santi-en-accion-rodando-por-vez-primera-865x1536.jpg 865w, https:\/\/sarandidigital.com\/uy\/wp-content\/uploads\/2026\/05\/Santi-en-accion-rodando-por-vez-primera.jpg 894w\" sizes=\"auto, (max-width: 577px) 100vw, 577px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Santiago Garc\u00eda en pleno rodaje, cumpliendo sus sue\u00f1os<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p>antiago Garc\u00eda es Santii \u2013as\u00ed se lo ubica en las redes sociales-, un joven sarandiense que estudia Odontolog\u00eda en la Universidad de la Rep\u00fablica y al mismo tiempo persigue sus sue\u00f1os actorales.<\/p>\n\n\n\n<p>Esa persecuci\u00f3n que es trabajosa, empinada, dura, frustrante a veces, le permiti\u00f3 ser convocado para participar de una producci\u00f3n audiovisual internacional de la plataforma Amazon Prime, concretamente la primera de generaci\u00f3n nacional.<\/p>\n\n\n\n<p>Con el liderazgo actoral de Natalia Oreiro, el joven oriundo de nuestra ciudad es parte del elenco que por estos d\u00edas trabaja en fase de rodaje, de cara a un estreno que se concretar\u00eda en la temporada 2027.<\/p>\n\n\n\n<p>La pel\u00edcula de la cual formar\u00e1 parte Santi tiene locaciones en nuestro pa\u00eds y significa el primer acercamiento del joven a la gran pantalla, un espacio en el que a juzgar por sus palabras, se siente c\u00f3modo.<\/p>\n\n\n\n<p><strong>Los primeros nervios<\/strong><\/p>\n\n\n\n<p>Nervioso, muy nervioso. As\u00ed dijo sentirse Santi cuando realiz\u00f3 su primera entrevista radial para 102.3 FM Digital, este lunes al mediod\u00eda. Tambi\u00e9n as\u00ed se sinti\u00f3 cuando fue convocado para su primer trabajo actoral. \u201cEs mi primera nota de este gran camino,&nbsp;y la verdad que para m\u00ed fue inmenso todo, s\u00faper grande,&nbsp;no pod\u00eda creer ni siquiera cuando me dieron la noticia&nbsp;ni cuando estaba yendo a producir\u201d, comienza contando.<\/p>\n\n\n\n<p>Es el principio de un camino que comenz\u00f3 en Sarand\u00ed Grande, grabando reels y subiendo fotos, para recalar en Montevideo.<\/p>\n\n\n\n<p>\u201cYo ahora estoy en Montevideo,&nbsp;y cuando vine para ac\u00e1 vine con el objetivo de abarcar todo lo que siempre so\u00f1\u00e9,&nbsp;porque obviamente en mi pueblo no hay muchas oportunidades,&nbsp;y cuando llegu\u00e9 ac\u00e1 en seguidita me puse manos a la obra,&nbsp;yo igual ya estaba como introduci\u00e9ndome a este mundo,&nbsp;porque era algo que siempre so\u00f1\u00e9\u201d. Habla constantemente de sue\u00f1os, de anhelos, de tener memoria infantil en la cual se ubica cercano a la tele, a su abuela.<\/p>\n\n\n\n<p>\u201cDesde que tengo memoria\u00a0siempre le dec\u00eda a mam\u00e1 y a mi abuela,\u00a0que siempre quer\u00eda estar en la tele,\u00a0siempre estaba como con esa imagen,\u00a0y adem\u00e1s sent\u00eda como la corazonada que uno siente de que algo lo espera,\u00a0y despu\u00e9s ese sentimiento se hizo cada vez m\u00e1s grande\u00a0y ahora que puedo tener la autonom\u00eda, el poder de decidir\u00a0qu\u00e9 quiero hacer con mi futuro, me atrev\u00ed a buscarlo. Lo que m\u00e1s me llama a m\u00ed es el actuar,\u00a0yo soy una persona que siempre est\u00e1 romantizando ideas,\u00a0o mismo creando desde el arte,\u00a0en mi mente, todo el tiempo, siempre que estoy aburrido,\u00a0siempre me imagino escenas y cosas as\u00ed. Como que es esto lo que me gusta, me imagino -obviamente siempre hablo desde la humildad,\u00a0yo no quiero sonar s\u00faper loco- yendo hacia la gran pantalla. Siempre me imagin\u00e9 ah\u00ed y ahora mismo es mi gran objetivo\u201d, le cuenta a 102.3 FM.<\/p>\n\n\n\n<p><strong>Un duro camino<\/strong><\/p>\n\n\n\n<p>Observar las redes de Santi es adentrarse en un mundo de fotos y videos donde la imagen lo es todo. Es parte del camino a recorrer, mostrar y mostrarse.<\/p>\n\n\n\n<p>Del mismo modo con las agencias y plataformas, en las cuales se debe tener presencia para finalmente, un d\u00eda, ser convocado.<\/p>\n\n\n\n<p>\u201cHa sido muy dif\u00edcil,&nbsp;yo me acuerdo que en mi cuarto, con mi hoja,&nbsp;preparaba mis guiones, y me inventaba reels&nbsp;para envi\u00e1rselo a las agencias. Tardaba tardes, d\u00edas, produciendo eso. Despu\u00e9s me dec\u00edan que no. Tambi\u00e9n me sacaba fotos, me hac\u00eda mis propias producciones en mi cuarto&nbsp;y una vez que las terminaba, se las mandaba,&nbsp;y me dec\u00edan que no muchas veces. A veces ni me respond\u00edan pero nunca me rend\u00ed. Obviamente no estoy en un lugar gigante,&nbsp;pero di el primer paso hacia lo grande que se viene,&nbsp;y creo que eso fue lo que me mantuvo\u201d, se\u00f1ala el joven que curs\u00f3 el Liceo Faustino Harrison y hoy estudia en Udelar.<\/p>\n\n\n\n<p>Consultado sobre la necesidad de contar con agencia de talentos o representante para aspirar a tener una carrera en este mundo tan competitivo, se\u00f1ala que si aunque personalmente a\u00fan no tiene una agencia fija que le represente.<\/p>\n\n\n\n<p>\u201cEstoy en la b\u00fasqueda, sigo a\u00fan en la b\u00fasqueda,&nbsp;pero a m\u00ed me contact\u00f3 la agencia que se encarga de esta producci\u00f3n porque yo hab\u00eda mandado mis im\u00e1genes m\u00e1s&nbsp;nunca hab\u00eda recibido respuesta. Me contactaron recientemente para formar parte&nbsp;y cuando le\u00ed se me cay\u00f3 el mundo,&nbsp;yo soy una persona s\u00faper sensible con los sue\u00f1os,&nbsp;y poder llegar y luchar y trabajar para ello,&nbsp;no s\u00e9 si se necesita una agencia pero s\u00ed se necesitan las ganas, el trabajo y la insistencia de estar\u201d.<\/p>\n\n\n\n<p><strong>Super producci\u00f3n<\/strong><\/p>\n\n\n\n<p>La producci\u00f3n de Amazon Prime Video es la primera que se desarrolla en forma \u00edntegra en Uruguay, habiendo iniciado su periplo hace ya varios meses.<\/p>\n\n\n\n<p>Se llama \u2018Te amo, te odio\u2019 y cuenta con el protag\u00f3nico de Natalia Oreiro. \u201cTambi\u00e9n est\u00e1 Pablo, un actor joven muy incre\u00edble,&nbsp;y son personas que yo miro y no pod\u00eda creer que estaba compartiendo el set con ellos. Yo desde un pueblo insist\u00ed, insist\u00ed,&nbsp;y por fin se me dio la oportunidad,&nbsp;la verdad que es incre\u00edble. En mi rol la c\u00e1mara me sigue, actu\u00e9 como el amante de la novia del principal,&nbsp;entonces ten\u00eda que tratar de seducirla a ella. Esta fue mi primera experiencia frente a c\u00e1maras en sesiones muy cansadoras,&nbsp;estaba lleno de nervios,&nbsp;pero esos nervios que sent\u00eds cuando est\u00e1s haciendo lo que te gusta. Cuando dicen acci\u00f3n, inmediatamente entra el personaje en m\u00ed. Cuando hicieron el corte no pod\u00eda creer lo que hab\u00eda hecho,&nbsp;fue totalmente incre\u00edble.&nbsp;A\u00fan no hemos tenido la oportunidad de ver algo,&nbsp;lo \u00fanico que llegu\u00e9 a ver fueron grabaciones del monitor\u201d, destacando que el equipo de producci\u00f3n cuid\u00f3 de muy buena forma al equipo actoral.<\/p>\n\n\n\n<p>\u201cFue una jornada donde hizo mucho fr\u00edo\u00a0y todo el tiempo se nos estaba cuidando de no pasar fr\u00edo,\u00a0tambi\u00e9n llov\u00eda, se nos cuidaba sobre eso,\u00a0nos trasladaban con enormes cuidados,\u00a0tambi\u00e9n nos pudimos alimentar durante la larga jornada,\u00a0que fueron alrededor de 16 horas. Comenz\u00f3 a las 4 de la madrugada y fue incre\u00edble el trato que ten\u00edan. La verdad me encantar\u00eda hacer esto toda mi vida,\u00a0s\u00faper emocionado y s\u00faper agradecido\u201d; confiesa en di\u00e1logo con la radio comunitaria.<\/p>\n\n\n\n<p>Esta oportunidad actoral se dio a partir de Amazon Latinoam\u00e9rica, con estreno previsto para el a\u00f1o pr\u00f3ximo. Mientras tanto, el sue\u00f1o contin\u00faa.<\/p>\n\n\n\n<p><strong>Lo que viene<\/strong><\/p>\n\n\n\n<p>\u201cA\u00fan sigo en la b\u00fasqueda&nbsp;y se vienen cositas muy lindas,&nbsp;es verdadero, se vienen cositas&nbsp;y me tienen muy emocionado, me tienen muy entusiasmado,&nbsp;la verdad que me levanto con emoci\u00f3n enorme,&nbsp;me tiene muy contento porque el camino sigue&nbsp;y las oportunidades que vienen yo las acepto,&nbsp;porque obviamente los peque\u00f1os pasitos te hacen gigante\u201d, nos dice el joven sarandiense cuando le preguntamos por el futuro.<\/p>\n\n\n\n<p>Alimentando ese tiempo por venir, Santi se est\u00e1 formando en talleres municipales de teatro, en la capital del pa\u00eds.<\/p>\n\n\n\n<p>De all\u00ed valora el hecho de que sean talleres gratuitos y el trabajo \u201ccon personas que tambi\u00e9n tienen la misma pasi\u00f3n, personas de distintas edades, distinta diversidad,&nbsp;obviamente te hace crecer un mont\u00f3n\u201d.<\/p>\n\n\n\n<p>A todo esto, contin\u00faa estudiando Odontolog\u00eda, una carrera \u201cpor la cual&nbsp;mis padres est\u00e1n haciendo un gran esfuerzo para mantenerme en esta situaci\u00f3n,&nbsp;y yo sigo de la mano con la carrera&nbsp;y estoy abierto a la oportunidad,&nbsp;sigo meti\u00e9ndole a la actuaci\u00f3n que es lo que a m\u00ed me hace feliz&nbsp;y me encantar\u00eda un d\u00eda ser el personaje principal,&nbsp;o hacer jornadas largu\u00edsimas de grabaci\u00f3n,&nbsp;la verdad que me canso, pero me encanta\u201d.<\/p>\n\n\n\n<p>Desde su presente, Santi les habla a los j\u00f3venes de la ciudad que persiguen sus sue\u00f1os, desde la m\u00fasica al deporte, desde los estudios al trabajo.<\/p>\n\n\n\n<p>\u201cSon los chicos que ahora est\u00e1n cumpliendo sus sue\u00f1os,&nbsp;el pueblo tambi\u00e9n, son personas incre\u00edbles&nbsp;que se animaron y lucharon por ello,&nbsp;obviamente hay un mont\u00f3n de trabajo detr\u00e1s,&nbsp;y yo le dir\u00eda, incluso me digo a m\u00ed del pasado,&nbsp;a esos chicos que tienen sue\u00f1os,&nbsp;que no se animan por ser de una ciudad muy chiquita,&nbsp;que nunca dejen de creer en ellos mismos,&nbsp;y que el desaf\u00edo no es conformar a la gente,&nbsp;sino ser uno mismo todo el tiempo y luchar por lo que uno siente,&nbsp;porque uno sabe que es eso y es darle con eso\u201d, concluye desde su entusiasmo.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrevista mantenida con el joven actor en el Noticiero &#8216;Siglo XXI&#8217; antiago Garc\u00eda es Santii \u2013as\u00ed se lo ubica en las redes sociales-, un joven sarandiense que estudia Odontolog\u00eda en la Universidad de la Rep\u00fablica y al mismo tiempo persigue sus sue\u00f1os actorales. Esa persecuci\u00f3n que es trabajosa, empinada, dura, frustrante a veces, le permiti\u00f3 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-575","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/posts\/575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/comments?post=575"}],"version-history":[{"count":1,"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/posts\/575\/revisions"}],"predecessor-version":[{"id":578,"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/posts\/575\/revisions\/578"}],"wp:attachment":[{"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/media?parent=575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/categories?post=575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sarandidigital.com\/uy\/wp-json\/wp\/v2\/tags?post=575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}